{"id":1527,"date":"2023-06-07T09:44:29","date_gmt":"2023-06-07T07:44:29","guid":{"rendered":"https:\/\/lecedrare.it\/?page_id=1527"},"modified":"2023-06-14T10:11:09","modified_gmt":"2023-06-14T08:11:09","slug":"cadillac-limousine-service","status":"publish","type":"page","link":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/","title":{"rendered":"Cadillac Limousine Service"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-flex-container fusion-parallax-none hundred-percent-fullwidth non-hundred-percent-height-scrolling lazyload fusion-custom-z-index\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:1;--awb-padding-top:10%;--awb-padding-right:1px;--awb-padding-bottom:10%;--awb-padding-left:1px;--awb-padding-top-medium:5%;--awb-padding-bottom-medium:5%;--awb-padding-top-small:5%;--awb-padding-bottom-small:5%;--awb-margin-top:0px;--awb-margin-bottom:3px;--awb-margin-top-medium:0px;--awb-margin-top-small:0px;--awb-background-size:cover;--awb-flex-wrap:wrap;\" data-bg=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze.jpg\" ><\/p>\n<div class=\"fusion-builder-row fusion-row fusion-flex-align-items-flex-start fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_4_5 4_5 fusion-flex-column fusion-animated\" style=\"--awb-padding-top:10%;--awb-padding-right:5%;--awb-padding-bottom:10%;--awb-padding-left:5%;--awb-padding-top-medium:20%;--awb-padding-bottom-medium:0px;--awb-padding-left-medium:5%;--awb-padding-top-small:20%;--awb-padding-left-small:5%;--awb-bg-size:cover;--awb-width-large:80%;--awb-margin-top-large:0px;--awb-spacing-right-large:2.4%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:2.4%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\" data-animationType=\"fadeInUp\" data-animationDuration=\"1.3\" data-animationOffset=\"top-into-view\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-row\">\n<div class=\"fusion-title title fusion-title-1 fusion-no-small-visibility fusion-sep-none fusion-title-text fusion-title-size-one\" style=\"--awb-text-color:#ffffff;--awb-margin-right:30%;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-margin-right-medium:0px;--awb-sep-color:#e2e2e2;--awb-font-size:73px;\"><h1 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Poppins&quot;;font-style:normal;font-weight:600;margin:0;letter-spacing:-2px;font-size:1em;--fontSize:73;line-height:1.12;text-shadow:5px 5px 13px #000000;\">Cadillac Limousine Service<\/h1><\/div>\n<div class=\"fusion-title title fusion-title-2 fusion-no-medium-visibility fusion-no-large-visibility fusion-sep-none fusion-title-text fusion-title-size-two\" style=\"--awb-text-color:#ffffff;--awb-margin-right:30%;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:30px;--awb-margin-left-small:0px;--awb-margin-right-medium:0px;--awb-sep-color:#e2e2e2;--awb-font-size:55px;\"><h2 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Poppins&quot;;font-style:normal;font-weight:600;margin:0;letter-spacing:-2px;text-transform:none;font-size:1em;--fontSize:55;line-height:1.09;text-shadow:5px 5px 13px #000000;\">Cadillac Limousine Service<\/h2><\/div>\n<div class=\"fusion-title title fusion-title-3 fusion-sep-none fusion-title-text fusion-title-size-four\" style=\"--awb-text-color:#ffffff;--awb-margin-right:30%;--awb-margin-bottom:30px;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:10px;--awb-margin-left-small:0px;--awb-margin-right-medium:0px;--awb-sep-color:#e2e2e2;--awb-font-size:2.1em;\"><h4 class=\"fusion-title-heading title-heading-left fusion-responsive-typography-calculated\" style=\"font-family:&quot;Lora&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;--fontSize:35.7;line-height:var(--awb-typography1-line-height);text-shadow:5px 5px 10px #000000;\">A special day with a unique event deserves the chance for something even rarer.<\/h4><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-2 fusion-flex-container nonhundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-custom-z-index\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:1;--awb-padding-top:2%;--awb-padding-right:2%;--awb-padding-bottom:2%;--awb-padding-left:2%;--awb-padding-right-medium:2%;--awb-padding-left-medium:2%;--awb-padding-right-small:7%;--awb-padding-bottom-small:0%;--awb-padding-left-small:7%;--awb-background-image:linear-gradient(180deg, #ffffff 0%,#e3e3e3 90%);--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"max-width:1996.8px;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-1 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-0 fusion_builder_column_inner_3_5 3_5 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:60%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.2%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.2%;--awb-width-medium:80%;--awb-order-medium:0;--awb-spacing-right-medium:2.4%;--awb-spacing-left-medium:2.4%;--awb-width-small:83.333333333333%;--awb-order-small:0;--awb-spacing-right-small:2.304%;--awb-spacing-left-small:2.304%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-text fusion-text-1 fusion-text-no-margin titoloristorante\" style=\"--awb-content-alignment:center;--awb-font-size:2.5em;--awb-line-height:1.2em;--awb-text-color:#282828;--awb-margin-top:20px;--awb-margin-bottom:20px;--awb-text-font-family:&quot;Lora&quot;;--awb-text-font-style:normal;--awb-text-font-weight:600;\"><p>Marcantonio likes to call himself as a &#8220;Chef with a healthy passion for American motors&#8221;.<\/p>\n<\/div>\n<div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:1%;margin-bottom:1%;width:100%;max-width:25%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d9d9d9;border-color:#d9d9d9;border-top-width:5px;\"><\/div><\/div>\n<div class=\"fusion-text fusion-text-2 fusion-text-no-margin testooristorante\" style=\"--awb-content-alignment:center;--awb-text-color:#282828;--awb-margin-top:20px;--awb-margin-bottom:20px;--awb-text-font-family:&quot;Poppins&quot;;--awb-text-font-style:normal;--awb-text-font-weight:500;\"><p>After a thorough conservation-type restoration, his &#8217;58 <strong>Caddy<\/strong> is now available for you to enjoy a <strong>rare and exclusive experience<\/strong>.<\/p>\n<\/div>\n<\/div><\/div>\n<\/div>\n<div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-1 lightbox-enabled\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"yes\" data-autoplayspeed=\"7000\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"3\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"10\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:3;--awb-column-spacing:10px;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-1.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-2.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-3.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_1]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-4.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-3 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-30px;--awb-margin-top-small:-5px;--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-section-separator section-separator hills-opacity fusion-section-separator-1\" style=\"--awb-spacer-padding-top:inherit;--awb-divider-height:200px;--awb-spacer-height:200px;--awb-divider-height-medium:150px;--awb-spacer-height-medium:150px;--awb-divider-height-small:100px;--awb-spacer-height-small:100px;--awb-sep-font-size:0;--awb-sep-line-height:0;\"><div class=\"fusion-section-separator-svg\"><svg class=\"fusion-hills-opacity-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" viewBox=\"0 0 1024 182\" preserveAspectRatio=\"none\" fill=\"rgba(227,227,227,1)\"><path class=\"st0\" d=\"M0 0h1024v140.5C995.9 162 963.9 178 926.9 178c-112.8 0-198.1-93.8-289.8-93.8s-199.5 91-285.3 91-142.2-82.1-238.5-82.1c-63.1 0-75.7 31.6-113.3 53.6V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st1\" d=\"M1024 0v75.9C984.3 60 942.2 48.6 905.3 50.1c-110.4 4.5-191.8 109.8-325.5 116.2C470.6 171.5 235.6 46.1 150.3 0H1024z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st2\" d=\"M0 0h1024v92c-57.5 30.9-116.9 73.7-199.9 75-133.8 2-158.9-87.9-342-87.9S202.1 183.7 74.2 182c-27.8-.3-52.4-4.2-74.2-9.7V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st3\" d=\"M0 0h1024v101.6C986.8 82 943.3 66.3 884.4 65.4 733.3 63 742.8 94 585.9 94.6S447 47.6 280.4 50.9C132.8 53.6 91.2 137.5 0 154V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st4\" d=\"M0 0h1024v77.3c-49-20.1-120.5-42.4-193.2-42.1-128.9.5-159.8 72.3-255.8 72.3-89.1 0-134.7-80.2-245-82-110.4-1.8-160.9 57.2-280 59.2-17.2.3-33.9-1.8-50-5.7V0z\"\/>\n\t\t\t\t\t\t\t\t<\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div>\n<p><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-4 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-custom-z-index\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:1;--awb-padding-top-small:0px;--awb-margin-top:-6%;--awb-margin-top-medium:-120px;--awb-margin-top-small:-90px;--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-2 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-padding-right:4%;--awb-padding-left:4%;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:83.333333333333%;--awb-order-medium:0;--awb-spacing-right-medium:2.304%;--awb-spacing-left-medium:2.304%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-title title fusion-title-4 fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:#000000;--awb-margin-top:6%;--awb-margin-bottom:6%;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-margin-right-medium:0px;--awb-sep-color:#e2e2e2;--awb-font-size:1.7em;\"><h3 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"font-family:&quot;Lora&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;--fontSize:28.9;line-height:1.06;\">Restoration of the 1958 Cadillac 75 Series<\/p><\/h3><\/div>\n<div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:1%;margin-bottom:1%;width:100%;max-width:25%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d9d9d9;border-color:#d9d9d9;border-top-width:5px;\"><\/div><\/div>\n<div class=\"fusion-text fusion-text-3 fusion-text-no-margin testooristorante\" style=\"--awb-content-alignment:center;--awb-text-color:#000000;--awb-margin-top:40px;--awb-margin-bottom:40px;--awb-text-font-family:&quot;Poppins&quot;;--awb-text-font-style:normal;--awb-text-font-weight:500;\"><p>It is 2007 when Marcantonio manages to find an original <strong>American car from the 1950s-60s<\/strong> that he was looking for so much.<\/p>\n<p>It is love at first sight when he &#8220;meets&#8221; her, a <strong>1958 Cadillac 75 series<\/strong> limousine, and something inside his heart suggests that this &#8220;lady&#8221; can be his car.<\/p>\n<p>Marcantonio is conscious of being in front of a <strong>piece of American history<\/strong>, so he buys this unobtainable car; only 630 examples were produced, 4 or 5 of them only are now circulating worldwide.<\/p>\n<\/div>\n<div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-xlarge button-custom fusion-button-default button-1 fusion-button-default-span \" style=\"--awb-margin-bottom:30px;--button_accent_color:#ffffff;--button_border_color:#e3e3e3;--button_accent_hover_color:#000000;--button_border_hover_color:#000000;--button_gradient_top_color:#000000;--button_gradient_bottom_color:#000000;--button_gradient_top_color_hover:rgba(255,255,255,0);--button_gradient_bottom_color_hover:rgba(255,255,255,0);--button_text_transform:uppercase;\" target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Storia-del-restauro-Cadillac-75-limousine-Marcantonio-Sagramoso.pdf\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Read the full story<\/span><\/a><\/div>\n<\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-3 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-top-medium:-30px;--awb-margin-top-small:-30px;--awb-margin-bottom-small:10px;--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-1 hover-type-zoomin\"><a href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[location]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\" alt class=\"lazyload img-responsive wp-image-1390\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 980px) 100vw, 1200px\" \/><\/a><\/span><\/div>\n<div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-1 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-top:8%;--awb-margin-top-medium:8%;--awb-margin-top-small:3%;--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-2 hover-type-zoomin\"><a href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[location]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6.jpg\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6.jpg\" alt class=\"lazyload img-responsive wp-image-1391\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-6.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 980px) 100vw, 1200px\" \/><\/a><\/span><\/div>\n<\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-2 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-top:8%;--awb-margin-top-medium:8%;--awb-margin-top-small:3%;--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-3 hover-type-zoomin\"><a href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[location]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7.jpg\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7.jpg\" alt class=\"lazyload img-responsive wp-image-1392\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-7.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 980px) 100vw, 1200px\" \/><\/a><\/span><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-5 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling fusion-custom-z-index\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-z-index:1;--awb-padding-bottom:2%;--awb-padding-bottom-medium:0px;--awb-padding-bottom-small:0px;--awb-margin-top:10px;--awb-margin-top-medium:-10px;--awb-margin-top-small:-30px;--awb-background-image:linear-gradient(180deg, #ffffff 0%,#e3e3e3 90%);--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-4 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-2 lightbox-enabled\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"yes\" data-autoplayspeed=\"7000\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"3\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"10\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:3;--awb-column-spacing:10px;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-8.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-9.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-10.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_2]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-11.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-6 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-30px;--awb-margin-top-small:-3px;--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-section-separator section-separator hills-opacity fusion-section-separator-2\" style=\"--awb-spacer-padding-top:inherit;--awb-divider-height:200px;--awb-spacer-height:200px;--awb-divider-height-medium:150px;--awb-spacer-height-medium:150px;--awb-divider-height-small:100px;--awb-spacer-height-small:100px;--awb-sep-font-size:0;--awb-sep-line-height:0;\"><div class=\"fusion-section-separator-svg\"><svg class=\"fusion-hills-opacity-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" viewBox=\"0 0 1024 182\" preserveAspectRatio=\"none\" fill=\"rgba(227,227,227,1)\"><path class=\"st0\" d=\"M0 0h1024v140.5C995.9 162 963.9 178 926.9 178c-112.8 0-198.1-93.8-289.8-93.8s-199.5 91-285.3 91-142.2-82.1-238.5-82.1c-63.1 0-75.7 31.6-113.3 53.6V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st1\" d=\"M1024 0v75.9C984.3 60 942.2 48.6 905.3 50.1c-110.4 4.5-191.8 109.8-325.5 116.2C470.6 171.5 235.6 46.1 150.3 0H1024z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st2\" d=\"M0 0h1024v92c-57.5 30.9-116.9 73.7-199.9 75-133.8 2-158.9-87.9-342-87.9S202.1 183.7 74.2 182c-27.8-.3-52.4-4.2-74.2-9.7V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st3\" d=\"M0 0h1024v101.6C986.8 82 943.3 66.3 884.4 65.4 733.3 63 742.8 94 585.9 94.6S447 47.6 280.4 50.9C132.8 53.6 91.2 137.5 0 154V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st4\" d=\"M0 0h1024v77.3c-49-20.1-120.5-42.4-193.2-42.1-128.9.5-159.8 72.3-255.8 72.3-89.1 0-134.7-80.2-245-82-110.4-1.8-160.9 57.2-280 59.2-17.2.3-33.9-1.8-50-5.7V0z\"\/>\n\t\t\t\t\t\t\t\t<\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div>\n<\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-7 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top-medium:0px;--awb-margin-top:-10%;--awb-margin-top-medium:-120px;--awb-margin-top-small:-95px;--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-5 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-title title fusion-title-5 fusion-no-large-visibility fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:#000000;--awb-margin-top:6%;--awb-margin-bottom:10%;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:60px;--awb-margin-left-small:0px;--awb-margin-right-medium:0px;--awb-sep-color:#e2e2e2;--awb-font-size:1.7em;\"><h3 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"font-family:&quot;Lora&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;--fontSize:28.9;line-height:1.06;\">Cadillac Limousine service: an exclusive and elegant car will accompany you on your movements, ensuring an exciting and unrepeatable experience.<\/h3><\/div>\n<div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-top:3%;--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-4 hover-type-zoomin\"><a href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[location]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12.jpg\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12.jpg\" alt class=\"lazyload img-responsive wp-image-1397\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-12.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 980px) 100vw, 1200px\" \/><\/a><\/span><\/div>\n<div class=\"fusion-builder-row fusion-builder-row-inner fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"--awb-flex-grow:0;--awb-flex-grow-medium:0;--awb-flex-grow-small:0;--awb-flex-shrink:0;--awb-flex-shrink-medium:0;--awb-flex-shrink-small:0;width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-3 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-top:8%;--awb-margin-top-medium:8%;--awb-margin-top-small:3%;--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-5 hover-type-zoomin\"><a href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[location]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13.jpg\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13.jpg\" alt class=\"lazyload img-responsive wp-image-1398\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-13.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 980px) 100vw, 1200px\" \/><\/a><\/span><\/div>\n<\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column_inner fusion-builder-nested-column-4 fusion_builder_column_inner_1_2 1_2 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:50%;--awb-order-medium:0;--awb-spacing-right-medium:3.84%;--awb-spacing-left-medium:3.84%;--awb-width-small:50%;--awb-order-small:0;--awb-spacing-right-small:3.84%;--awb-spacing-left-small:3.84%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-element\" style=\"text-align:center;--awb-margin-top:8%;--awb-margin-top-medium:8%;--awb-margin-top-small:3%;--awb-max-width:100%;--awb-caption-title-font-family:var(--h2_typography-font-family);--awb-caption-title-font-weight:var(--h2_typography-font-weight);--awb-caption-title-font-style:var(--h2_typography-font-style);--awb-caption-title-size:var(--h2_typography-font-size);--awb-caption-title-transform:var(--h2_typography-text-transform);--awb-caption-title-line-height:var(--h2_typography-line-height);--awb-caption-title-letter-spacing:var(--h2_typography-letter-spacing);\"><span class=\" fusion-imageframe imageframe-none imageframe-6 hover-type-zoomin\"><a href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14.jpg\" class=\"fusion-lightbox\" data-rel=\"iLightbox[location]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14.jpg\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14.jpg\" alt class=\"lazyload img-responsive wp-image-1399\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-14.jpg 1920w\" data-sizes=\"auto\" data-orig-sizes=\"(max-width: 980px) 100vw, 1200px\" \/><\/a><\/span><\/div>\n<\/div><\/div><\/div>\n<\/div><\/div>\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-6 fusion_builder_column_1_2 1_2 fusion-flex-column\" style=\"--awb-padding-right:4%;--awb-bg-size:cover;--awb-width-large:50%;--awb-margin-top-large:0px;--awb-spacing-right-large:3.84%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:3.84%;--awb-width-medium:80%;--awb-order-medium:0;--awb-spacing-right-medium:2.4%;--awb-spacing-left-medium:2.4%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-title title fusion-title-6 fusion-no-small-visibility fusion-no-medium-visibility fusion-sep-none fusion-title-center fusion-title-text fusion-title-size-three\" style=\"--awb-text-color:#000000;--awb-margin-top:6%;--awb-margin-bottom:6%;--awb-margin-top-small:10px;--awb-margin-right-small:0px;--awb-margin-bottom-small:20px;--awb-margin-left-small:0px;--awb-margin-right-medium:0px;--awb-sep-color:#e2e2e2;--awb-font-size:1.7em;\"><h3 class=\"fusion-title-heading title-heading-center fusion-responsive-typography-calculated\" style=\"font-family:&quot;Lora&quot;;font-style:normal;font-weight:600;margin:0;font-size:1em;--fontSize:28.9;line-height:1.06;\">Cadillac Limousine service: an exclusive and elegant car will accompany you on your movements, ensuring an exciting and unrepeatable experience.<\/h3><\/div>\n<div class=\"fusion-separator\" style=\"align-self: center;margin-left: auto;margin-right: auto;margin-top:1%;margin-bottom:1%;width:100%;max-width:25%;\"><div class=\"fusion-separator-border sep-single sep-solid\" style=\"--awb-height:20px;--awb-amount:20px;--awb-sep-color:#d9d9d9;border-color:#d9d9d9;border-top-width:5px;\"><\/div><\/div>\n<div class=\"fusion-text fusion-text-4 fusion-text-no-margin testooristorante\" style=\"--awb-content-alignment:center;--awb-text-color:#000000;--awb-margin-top:40px;--awb-margin-bottom:40px;--awb-text-font-family:&quot;Poppins&quot;;--awb-text-font-style:normal;--awb-text-font-weight:500;\"><p>After two years of working, modifications, and conservative restorations, alternated with more than difficult choices and moments of discouragement, sustained only by an endless dose of patience and personal motivation, the Caddy now looks like it just walked out of a 60-year-old Car Store.<\/p>\n<p>Caddy is <strong>at your disposal<\/strong> if you want to give yourself a unique gift on your most special day.<\/p>\n<\/div>\n<div style=\"text-align:center;\"><a class=\"fusion-button button-flat button-xlarge button-custom fusion-button-default button-2 fusion-button-default-span \" style=\"--button_accent_color:#000000;--button_border_color:#000000;--button_accent_hover_color:#ffffff;--button_border_hover_color:rgba(255,255,255,0);--button_gradient_top_color:rgba(255,255,255,0);--button_gradient_bottom_color:rgba(255,255,255,0);--button_gradient_top_color_hover:#000000;--button_gradient_bottom_color_hover:#000000;--button_text_transform:uppercase;\" target=\"_self\" href=\"https:\/\/lecedrare.it\/en\/reservations\/\"><span class=\"fusion-button-text awb-button__text awb-button__text--default\">Request information<\/span><\/a><\/div>\n<\/div><\/div>\n<\/div>\n<p><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-8 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-100px;--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-section-separator section-separator hills-opacity fusion-section-separator-3\" style=\"--awb-spacer-padding-top:inherit;--awb-divider-height:200px;--awb-spacer-height:200px;--awb-divider-height-medium:150px;--awb-spacer-height-medium:150px;--awb-divider-height-small:100px;--awb-spacer-height-small:100px;--awb-sep-font-size:0;--awb-sep-line-height:0;\"><div class=\"fusion-section-separator-svg\"><svg class=\"fusion-hills-opacity-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" viewBox=\"0 -0.5 1024 182\" preserveAspectRatio=\"none\" fill=\"rgba(227,227,227,1)\"><path class=\"st0\" d=\"M0 182.086h1024V41.593c-28.058-21.504-60.109-37.581-97.075-37.581-112.845 0-198.144 93.798-289.792 93.798S437.658 6.777 351.846 6.777s-142.234 82.125-238.49 82.125c-63.078 0-75.776-31.744-113.357-53.658L0 182.086z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st1\" d=\"M1024 181.062v-75.878c-39.731 15.872-80.794 27.341-117.658 25.805-110.387-4.506-191.795-109.773-325.53-116.224-109.158-5.12-344.166 120.115-429.466 166.298H1024v-.001z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st2\" d=\"M0 182.086h1024V90.028C966.451 59.103 907.059 16.3 824.115 15.071 690.278 13.023 665.19 102.93 482.099 102.93S202.138-1.62 74.24.019C46.49.326 21.811 4.217 0 9.849v172.237z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st3\" d=\"M0 182.086h1024V80.505c-37.171 19.558-80.691 35.328-139.571 36.25-151.142 2.355-141.619-28.57-298.496-29.184s-138.854 47.002-305.459 43.725C132.813 128.428 91.238 44.563 0 28.179v153.907z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st4\" d=\"M0 182.086h1024v-77.312c-49.05 20.07-120.525 42.394-193.229 42.086-128.922-.512-159.846-72.294-255.795-72.294-89.088 0-134.656 80.179-245.043 82.022S169.063 99.346 49.971 97.401C32.768 97.094 16.077 99.244 0 103.135v78.951z\"\/>\n\t\t\t\t\t\t\t\t<\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div>\n<p><\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-9 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-padding-top-small:25px;--awb-margin-top:0px;--awb-background-image:linear-gradient(180deg, #e3e3e3 0%,#e3e3e3 90%);--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-builder-row fusion-row fusion-flex-align-items-center fusion-flex-justify-content-center fusion-flex-content-wrap\" style=\"width:104% !important;max-width:104% !important;margin-left: calc(-4% \/ 2 );margin-right: calc(-4% \/ 2 );\">\n<div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-7 fusion_builder_column_1_1 1_1 fusion-flex-column\" style=\"--awb-bg-size:cover;--awb-width-large:100%;--awb-margin-top-large:0px;--awb-spacing-right-large:1.92%;--awb-margin-bottom-large:20px;--awb-spacing-left-large:1.92%;--awb-width-medium:100%;--awb-order-medium:0;--awb-spacing-right-medium:1.92%;--awb-spacing-left-medium:1.92%;--awb-width-small:100%;--awb-order-small:0;--awb-spacing-right-small:1.92%;--awb-spacing-left-small:1.92%;\"><div class=\"fusion-column-wrapper fusion-column-has-shadow fusion-flex-justify-content-flex-start fusion-content-layout-column\">\n<div class=\"fusion-image-carousel fusion-image-carousel-auto fusion-image-carousel-3 lightbox-enabled\"><div class=\"awb-carousel awb-swiper awb-swiper-carousel awb-carousel--carousel awb-swiper-dots-position-bottom\" data-layout=\"carousel\" data-autoplay=\"yes\" data-autoplayspeed=\"7000\" data-autoplaypause=\"no\" data-loop=\"yes\" data-columns=\"3\" data-columnsmedium=\"1\" data-columnssmall=\"1\" data-itemmargin=\"10\" data-itemwidth=\"180\" data-touchscroll=\"no\" data-freemode=\"no\" data-imagesize=\"auto\" data-scrollitems=\"0\" data-centeredslides=\"no\" data-rotationangle=\"50\" data-depth=\"100\" data-speed=\"500\" data-shadow=\"no\" data-pagination=\"bullets\" style=\"--awb-columns:3;--awb-column-spacing:10px;\"><div class=\"swiper-wrapper awb-image-carousel-wrapper fusion-flex-align-items-center\"><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_3]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-15.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_3]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-16.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><div class=\"swiper-slide\"><div class=\"fusion-carousel-item-wrapper\"><div class=\"fusion-image-wrapper hover-type-zoomin\"><a data-rel=\"iLightbox[image_carousel_3]\" data-title=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" aria-label=\"Servizio Cadillac Limousine &#8211; Esperienze ristorante Le Cedrare\" href=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17.jpg\" target=\"_self\"><img decoding=\"async\" width=\"1920\" height=\"1280\" src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17.jpg\" class=\"attachment-full size-full lazyload\" alt=\"\" srcset=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%27http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%27%20width%3D%271920%27%20height%3D%271280%27%20viewBox%3D%270%200%201920%201280%27%3E%3Crect%20width%3D%271920%27%20height%3D%271280%27%20fill-opacity%3D%220%22%2F%3E%3C%2Fsvg%3E\" data-orig-src=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17.jpg\" data-srcset=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17-200x133.jpg 200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17-400x267.jpg 400w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17-600x400.jpg 600w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17-800x533.jpg 800w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17-1200x800.jpg 1200w, https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-17.jpg 1920w\" data-sizes=\"auto\" \/><\/a><\/div><\/div><\/div><\/div><div class=\"awb-swiper-button awb-swiper-button-prev\"><i class=\"awb-icon-angle-left\" aria-hidden=\"true\"><\/i><\/div><div class=\"awb-swiper-button awb-swiper-button-next\"><i class=\"awb-icon-angle-right\" aria-hidden=\"true\"><\/i><\/div><\/div><\/div>\n<\/div><\/div>\n<\/div>\n<\/div>\n<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-10 fusion-flex-container hundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"--awb-border-radius-top-left:0px;--awb-border-radius-top-right:0px;--awb-border-radius-bottom-right:0px;--awb-border-radius-bottom-left:0px;--awb-margin-top:-30px;--awb-margin-top-small:-3px;--awb-flex-wrap:wrap;\" ><\/p>\n<div class=\"fusion-section-separator section-separator hills-opacity fusion-section-separator-4\" style=\"--awb-spacer-padding-top:inherit;--awb-divider-height:200px;--awb-spacer-height:200px;--awb-divider-height-medium:150px;--awb-spacer-height-medium:150px;--awb-divider-height-small:100px;--awb-spacer-height-small:100px;--awb-sep-font-size:0;--awb-sep-line-height:0;\"><div class=\"fusion-section-separator-svg\"><svg class=\"fusion-hills-opacity-candy\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" version=\"1.1\" width=\"100%\" viewBox=\"0 0 1024 182\" preserveAspectRatio=\"none\" fill=\"rgba(227,227,227,1)\"><path class=\"st0\" d=\"M0 0h1024v140.5C995.9 162 963.9 178 926.9 178c-112.8 0-198.1-93.8-289.8-93.8s-199.5 91-285.3 91-142.2-82.1-238.5-82.1c-63.1 0-75.7 31.6-113.3 53.6V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st1\" d=\"M1024 0v75.9C984.3 60 942.2 48.6 905.3 50.1c-110.4 4.5-191.8 109.8-325.5 116.2C470.6 171.5 235.6 46.1 150.3 0H1024z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st2\" d=\"M0 0h1024v92c-57.5 30.9-116.9 73.7-199.9 75-133.8 2-158.9-87.9-342-87.9S202.1 183.7 74.2 182c-27.8-.3-52.4-4.2-74.2-9.7V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st3\" d=\"M0 0h1024v101.6C986.8 82 943.3 66.3 884.4 65.4 733.3 63 742.8 94 585.9 94.6S447 47.6 280.4 50.9C132.8 53.6 91.2 137.5 0 154V0z\"\/>\n\t\t\t\t\t\t\t\t\t<path class=\"st4\" d=\"M0 0h1024v77.3c-49-20.1-120.5-42.4-193.2-42.1-128.9.5-159.8 72.3-255.8 72.3-89.1 0-134.7-80.2-245-82-110.4-1.8-160.9 57.2-280 59.2-17.2.3-33.9-1.8-50-5.7V0z\"\/>\n\t\t\t\t\t\t\t\t<\/svg><\/div><div class=\"fusion-section-separator-spacer\"><div class=\"fusion-section-separator-spacer-height\"><\/div><\/div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":1390,"parent":1524,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"footnotes":""},"class_list":["post-1527","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<title>Cadillac Limousine Service | Le Cedrare Restaurant<\/title>\n<meta name=\"description\" content=\"Exclusive Cadillac Limousine service. It will take you on your transfers, ensuring an exciting and unrepeatable experience.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cadillac Limousine Service | Le Cedrare Restaurant\" \/>\n<meta property=\"og:description\" content=\"Exclusive Cadillac Limousine service. It will take you on your transfers, ensuring an exciting and unrepeatable experience.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/\" \/>\n<meta property=\"og:site_name\" content=\"Ristorante LeCedrare\" \/>\n<meta property=\"og:image\" content=\"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"17 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/\",\"url\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/\",\"name\":\"Cadillac Limousine Service | Le Cedrare Restaurant\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/lecedrare.it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/lecedrare.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\",\"description\":\"Exclusive Cadillac Limousine service. It will take you on your transfers, ensuring an exciting and unrepeatable experience.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/#primaryimage\",\"url\":\"https:\\\/\\\/lecedrare.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\",\"contentUrl\":\"https:\\\/\\\/lecedrare.it\\\/wp-content\\\/uploads\\\/2022\\\/09\\\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg\",\"width\":1920,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/experiences\\\/cadillac-limousine-service\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/le-cedrare\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Experiences\",\"item\":\"https:\\\/\\\/lecedrare.it\\\/en\\\/?page_id=1524\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cadillac Limousine Service\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/lecedrare.it\\\/#website\",\"url\":\"https:\\\/\\\/lecedrare.it\\\/\",\"name\":\"Ristorante LeCedrare\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/lecedrare.it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/lecedrare.it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/lecedrare.it\\\/#organization\",\"name\":\"Ristorante Le Cedrare\",\"url\":\"https:\\\/\\\/lecedrare.it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/lecedrare.it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/lecedrare.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Le-Cedrare-ristorante-Illasi-Verona-logo-seo.jpg\",\"contentUrl\":\"https:\\\/\\\/lecedrare.it\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/Le-Cedrare-ristorante-Illasi-Verona-logo-seo.jpg\",\"width\":740,\"height\":176,\"caption\":\"Ristorante Le Cedrare\"},\"image\":{\"@id\":\"https:\\\/\\\/lecedrare.it\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.instagram.com\\\/lecedrare\\\/\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/lecedrare\"]}]}<\/script>","yoast_head_json":{"title":"Cadillac Limousine Service | Le Cedrare Restaurant","description":"Exclusive Cadillac Limousine service. It will take you on your transfers, ensuring an exciting and unrepeatable experience.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/","og_locale":"en_US","og_type":"article","og_title":"Cadillac Limousine Service | Le Cedrare Restaurant","og_description":"Exclusive Cadillac Limousine service. It will take you on your transfers, ensuring an exciting and unrepeatable experience.","og_url":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/","og_site_name":"Ristorante LeCedrare","og_image":[{"width":1920,"height":1280,"url":"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"17 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/","url":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/","name":"Cadillac Limousine Service | Le Cedrare Restaurant","isPartOf":{"@id":"https:\/\/lecedrare.it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/#primaryimage"},"image":{"@id":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/#primaryimage"},"thumbnailUrl":"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg","description":"Exclusive Cadillac Limousine service. It will take you on your transfers, ensuring an exciting and unrepeatable experience.","breadcrumb":{"@id":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/#primaryimage","url":"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg","contentUrl":"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/09\/Servizio-cadillac-limousine-Le-Cedrare-esperienze-5.jpg","width":1920,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/lecedrare.it\/en\/experiences\/cadillac-limousine-service\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/lecedrare.it\/en\/le-cedrare\/"},{"@type":"ListItem","position":2,"name":"Experiences","item":"https:\/\/lecedrare.it\/en\/?page_id=1524"},{"@type":"ListItem","position":3,"name":"Cadillac Limousine Service"}]},{"@type":"WebSite","@id":"https:\/\/lecedrare.it\/#website","url":"https:\/\/lecedrare.it\/","name":"Ristorante LeCedrare","description":"","publisher":{"@id":"https:\/\/lecedrare.it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/lecedrare.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/lecedrare.it\/#organization","name":"Ristorante Le Cedrare","url":"https:\/\/lecedrare.it\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/lecedrare.it\/#\/schema\/logo\/image\/","url":"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/05\/Le-Cedrare-ristorante-Illasi-Verona-logo-seo.jpg","contentUrl":"https:\/\/lecedrare.it\/wp-content\/uploads\/2022\/05\/Le-Cedrare-ristorante-Illasi-Verona-logo-seo.jpg","width":740,"height":176,"caption":"Ristorante Le Cedrare"},"image":{"@id":"https:\/\/lecedrare.it\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.instagram.com\/lecedrare\/","https:\/\/www.youtube.com\/user\/lecedrare"]}]}},"_links":{"self":[{"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/pages\/1527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/comments?post=1527"}],"version-history":[{"count":5,"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/pages\/1527\/revisions"}],"predecessor-version":[{"id":1623,"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/pages\/1527\/revisions\/1623"}],"up":[{"embeddable":true,"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/pages\/1524"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/media\/1390"}],"wp:attachment":[{"href":"https:\/\/lecedrare.it\/en\/wp-json\/wp\/v2\/media?parent=1527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}